{"id":3709,"date":"2016-05-19T00:00:00","date_gmt":"2016-05-18T22:00:00","guid":{"rendered":"http:\/\/www.safram.com\/?p=3709"},"modified":"2019-12-11T17:39:50","modified_gmt":"2019-12-11T16:39:50","slug":"das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm","status":"publish","type":"post","link":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/","title":{"rendered":"Das Schweizer Segelteam Safram erweitert sein europ\u00e4isches Regattaprogramm"},"content":{"rendered":"<p><strong>Das im Jahr 2015 initiierte Regattaprogramm f\u00fcr den Genfer 35-Fuss Katamaran Safram war ein voller Erfolg: \u00a0Das Team hatte den Schweizer Segelsport an den bedeutendsten europ\u00e4ischen Binnenseeregatten vertreten und dabei vier der f\u00fcnf bestrittenen Rennen gewonnen. Das von Rodolphe Gautier geleitete Projekt hat auch 2016 erneut zum Ziel, den Schweizer Segelsport \u00fcber die Landesgrenzen hinaus bekannt zu machen und die Leidenschaft und Freude an diesem wunderbaren Sport zu wecken!<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1771\" style=\"width: 100%; height: auto;\" src=\"http:\/\/www.safram.com\/wp-content\/uploads\/2019\/12\/1.jpg\" alt=\"1\" width=\"1024\" height=\"565\" \/><\/p>\n<p><strong>Genf (Schweiz), den 19. Mai 2016 \u2013<\/strong> Safram, der Katamaran des Typs Ventilo M1, nimmt seit der Saison 2015 an den bedeutendsten europ\u00e4ischen Binnenseeregatten teil, vergleichbar mit der Bol d&#8217;Or Mirabaud auf dem Genfersee. In seiner ersten Saison holte sich das Team unter der Leitung von Rodolphe Gautier den Sieg an vier von insgesamt f\u00fcnf gesegelten Wettk\u00e4mpfen, es waren dies die Regatten: \u00a0<strong>Gen\u00e8ve-Rolle-Gen\u00e8ve (SUI) <\/strong>(250 Boote), <strong>Kekszalag (HUN)<\/strong> (580 Boote), die <strong>Trofeo Gorla<\/strong> und die <strong>Centomiglia (ITA)<\/strong> (180 Boote). 2016 nun wagt sich Safram anl\u00e4sslich der <strong>Regatta Rund Um <\/strong>(350 Boote) erstmals auf den Bodensee (Deutschland). Das Spezielle an diesem Rennen ist, dass es mehrheitlich in der Nacht gesegelt wird. Nach diesem Auftakt geht es dann zur\u00fcck auf den Genfersee und an die <strong>Bol d\u2019Or Mirabaud <\/strong>(520 Boote), welche das Team 2015 auf Rang zehn hinter der Armada der D35 beendet hatte.<\/p>\n<p>Um diesem Regattaprogramm etwas W\u00fcrze zu verleihen, wird sich das Team zu Beginn des Monats Juli hinaus aufs Salzwasser wagen und anl\u00e4sslich seiner Teilnahme an der ber\u00fchmten Regatta<strong> J.P. Morgan Asset Management Round The Island Race <\/strong>(England) reisen. Dieser Event bietet dem Team die einzigartige Chance, sich an anderen Teams und Bootsklassen zu messen (Ultime, Imoca, Maxi Yachts), die an die Verh\u00e4ltnisse im Solent besser angepasst sind. Es werden rund 1\u2018500 Boote erwartet.<\/p>\n<p>Aufgrund der Annullation der Regatta Tour de Belle Ile 2016 vor Trinit\u00e9-sur-mer (Frankreich), welche urspr\u00fcnglich Teil des Regattaprogramms war, f\u00fchrt der zweite Teil der Saison das Team Safram anl\u00e4sslich der <strong>Centomiglia<\/strong> nach Italien auf den windreichen Gardasee. Ein weiterer Leckerbissen k\u00fcndigt sich in Form der legend\u00e4ren <strong>Barcolana <\/strong>in Triest (Italien) an. Die ber\u00fchmte Regatta in der Adria bedenkt in naher Zukunft zu bieten auch Mehrrumpfbooten die Chance, teilzunehmen. Es werden insgesamt rund 1\u2018800 Boote erwartet.<\/p>\n<p>\u201eDas ganze Team hatte die Abenteuer, welche es in der vergangenen Saison in den entlegensten Ecken Europas erleben durfte, unglaublich genossen. Dieses Gef\u00fchl, eine bereichernde Erfahrung gemacht zu haben, ging weit \u00fcber das Erreichen irgendwelcher Ziele hinaus. Wir haben gesehen, dass das von Christian Favre designte Boot \u00e4usserst polyvalent ist, was es \u00fcber l\u00e4ngere Streckenabschnitte zu einer \u00ab Rennziege \u00bb macht. Dennoch bleibt der Katamaran auch bei auffrischendem Wind gut handelbar. Alle im Team haben Lust, aufs Meer hinaus zu gehen und diese Erfahrung zu machen, auch wenn dies nat\u00fcrlich eine gewaltige Herausforderung darstellt und wir S\u00fcsswassersegler uns warm anziehen m\u00fcssen\u201c, f\u00fcgt<strong> Rodolphe Gautier <\/strong>hinzu.<\/p>\n<p>Der High-Tech Mehrr\u00fcmpfer wird erneut von Christophe P\u00e9clard gesteuert werden, der den Winter dazu genutzt hat, neue Segel zu entwickeln. Damien Cardenoso wird das Team w\u00e4hrend den ersten beiden Regatten verst\u00e4rken, da Antoine Lauriot-Prevost verhindert ist. \u201eWir haben bis jetzt schon einige Testl\u00e4ufe absolvieren k\u00f6nnen und nutzen diese Trainings, bevor das Boot auseinander gebaut und nach Deutschland transportiert wird. Nat\u00fcrlich wollen wir stets unser Bestes geben und gute Resultate erzielen, dennoch ist es f\u00fcr uns alle in erster Linie unser Freizeitvergn\u00fcgen, weshalb das Hauptziel immer sein wird, an der ganzen Sache Spass zu haben\u201c, erinnert <strong>Fabian Racloz.<\/strong><\/p>\n<p>Das Unternehmen Safram, welches den Genfer Segelsport seit zehn Jahren unterst\u00fctzt, ist weitaus mehr als nur ein \u201eherk\u00f6mmlicher\u201c Partner f\u00fcr das Team. Es stellt den Seglern eigens einen Sattelschlepper zur Verf\u00fcgung, welcher \u00a0das Boot \u00fcberall hin transportiert. Safram ist ein europ\u00e4isches Transportunternehmen mit Schweizer Herkunft. Es hat seinen Firmenhauptsitz in Genf und bietet Kunden aus Industrie und Handel erstklassige Logistikdienstleistungen an. \u201eSafram w\u00fcnscht der M1 f\u00fcr die neue Saison stets guten Wind und freut sich darauf, die Abenteuer mit dem Team zu teilen!\u201c, erkl\u00e4rt Christophe Hottelier, Generaldirektor von Safram. Weitere Informationen zum Unternehmen erhalten Sie auf: <a href=\"https:\/\/www.safram.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.safram.com<\/a><\/p>\n<p>Gerne laden wir Sie dazu ein, alle Neuigkeiten zum Team \u00fcber die <a href=\"https:\/\/www.facebook.com\/SaframSailing\/?fref=ts\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook Seite von Safram Sailing<\/a>\u00a0mitzuverfolgen. Hier finden Sie aktuelle Posts, Fotos, Videos und Berichte zum Team.<\/p>\n<p><strong>Das Team \u00a02016:<\/strong><\/p>\n<ul>\n<li>Christophe Peclard &#8211; Steuermann<\/li>\n<li>Fabien Froesch &#8211; Nummer 1<\/li>\n<li>Fabian Racloz &#8211; Nummer 2<\/li>\n<li>Yves Guntern &#8211; Trimmer<\/li>\n<li>Antoine Lauriot-Prevost &#8211; Trimmer<\/li>\n<li>Damien Cardenoso &#8211; Trimmer<\/li>\n<li>Rodolphe Gautier &#8211; Trimmer \/ Skipper<\/li>\n<\/ul>\n<p><strong>Programm\u00a02016 :<\/strong><\/p>\n<ul>\n<li>Rund Um, Bodensee, Lindauer Segler-Club e.V (Deutschland): 3. Juni<\/li>\n<li>Bol d\u2019Or Mirabaud, Soci\u00e9t\u00e9 Nautique de Gen\u00e8ve (Schweiz) : 11. Juni<\/li>\n<li>J.P. Morgan Asset Management Round The Island Race, Island Sailing Club (England) : 2. Juli<\/li>\n<li>Centomiglia, Circolo Vela Gargnano (Italien): 10. September<\/li>\n<li>Barcolana, Societ\u00e0 Velica di Barcola e Gignano (Italien) : 9. Oktober<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1776\" style=\"width: 100%; height: auto;\" src=\"http:\/\/www.safram.com\/wp-content\/uploads\/2019\/12\/2.jpg\" alt=\"2\" width=\"1024\" height=\"725\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1777\" style=\"width: 100%; height: auto;\" src=\"http:\/\/www.safram.com\/wp-content\/uploads\/2019\/12\/2.jpg\" alt=\"3\" width=\"1024\" height=\"724\" \/><\/p>\n<p><strong>Fotos <\/strong>: \u00a9 Sophia Urban \/ MaxComm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das im Jahr 2015 initiierte Regattaprogramm f\u00fcr den Genfer 35-Fuss Katamaran Safram war ein voller Erfolg: \u00a0Das Team hatte den Schweizer Segelsport an den bedeutendsten europ\u00e4ischen<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":1163,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[92],"tags":[],"class_list":["post-3709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-corner-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das Schweizer Segelteam Safram erweitert sein europ\u00e4isches Regattaprogramm - Safram<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das Schweizer Segelteam Safram erweitert sein europ\u00e4isches Regattaprogramm - Safram\" \/>\n<meta property=\"og:description\" content=\"Das im Jahr 2015 initiierte Regattaprogramm f\u00fcr den Genfer 35-Fuss Katamaran Safram war ein voller Erfolg: \u00a0Das Team hatte den Schweizer Segelsport an den bedeutendsten europ\u00e4ischen [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/\" \/>\n<meta property=\"og:site_name\" content=\"Safram\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SaframFrance\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-18T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-11T16:39:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.safram.com\/wp-content\/uploads\/2019\/12\/1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"symediane\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"symediane\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\\\/\"},\"author\":{\"name\":\"symediane\",\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/#\\\/schema\\\/person\\\/5d3385f3956391d02bb98501605b1e39\"},\"headline\":\"Das Schweizer Segelteam Safram erweitert sein europ\u00e4isches Regattaprogramm\",\"datePublished\":\"2016-05-18T22:00:00+00:00\",\"dateModified\":\"2019-12-11T16:39:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\\\/\"},\"wordCount\":813,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.safram.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/1.jpg\",\"articleSection\":[\"Press corner\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\\\/\",\"url\":\"https:\\\/\\\/www.safram.com\\\/de\\\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\\\/\",\"name\":\"Das Schweizer Segelteam Safram erweitert sein europ\u00e4isches Regattaprogramm - Safram\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.safram.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/1.jpg\",\"datePublished\":\"2016-05-18T22:00:00+00:00\",\"dateModified\":\"2019-12-11T16:39:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.safram.com\\\/de\\\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.safram.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.safram.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/1.jpg\",\"width\":1024,\"height\":565},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.safram.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das Schweizer Segelteam Safram erweitert sein europ\u00e4isches Regattaprogramm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.safram.com\\\/de\\\/\",\"name\":\"Safram\",\"description\":\"Transporteur au coeur de l&#039;Europe\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.safram.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/#organization\",\"name\":\"Safram\",\"url\":\"https:\\\/\\\/www.safram.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www-test.safram.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/SAFRAM-LOGO.jpg\",\"contentUrl\":\"https:\\\/\\\/www-test.safram.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/SAFRAM-LOGO.jpg\",\"width\":567,\"height\":422,\"caption\":\"Safram\"},\"image\":{\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SaframFrance\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.safram.com\\\/de\\\/#\\\/schema\\\/person\\\/5d3385f3956391d02bb98501605b1e39\",\"name\":\"symediane\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aefaa550902b15b2c9beefb2a61934066e2a80665a770df239dcf4ea3547192c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aefaa550902b15b2c9beefb2a61934066e2a80665a770df239dcf4ea3547192c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aefaa550902b15b2c9beefb2a61934066e2a80665a770df239dcf4ea3547192c?s=96&d=mm&r=g\",\"caption\":\"symediane\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das Schweizer Segelteam Safram erweitert sein europ\u00e4isches Regattaprogramm - Safram","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/","og_locale":"de_DE","og_type":"article","og_title":"Das Schweizer Segelteam Safram erweitert sein europ\u00e4isches Regattaprogramm - Safram","og_description":"Das im Jahr 2015 initiierte Regattaprogramm f\u00fcr den Genfer 35-Fuss Katamaran Safram war ein voller Erfolg: \u00a0Das Team hatte den Schweizer Segelsport an den bedeutendsten europ\u00e4ischen [\u2026]","og_url":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/","og_site_name":"Safram","article_publisher":"https:\/\/www.facebook.com\/SaframFrance","article_published_time":"2016-05-18T22:00:00+00:00","article_modified_time":"2019-12-11T16:39:50+00:00","og_image":[{"width":1024,"height":565,"url":"https:\/\/www.safram.com\/wp-content\/uploads\/2019\/12\/1.jpg","type":"image\/jpeg"}],"author":"symediane","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"symediane","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/#article","isPartOf":{"@id":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/"},"author":{"name":"symediane","@id":"https:\/\/www.safram.com\/de\/#\/schema\/person\/5d3385f3956391d02bb98501605b1e39"},"headline":"Das Schweizer Segelteam Safram erweitert sein europ\u00e4isches Regattaprogramm","datePublished":"2016-05-18T22:00:00+00:00","dateModified":"2019-12-11T16:39:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/"},"wordCount":813,"commentCount":0,"publisher":{"@id":"https:\/\/www.safram.com\/de\/#organization"},"image":{"@id":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.safram.com\/wp-content\/uploads\/2019\/12\/1.jpg","articleSection":["Press corner"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/","url":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/","name":"Das Schweizer Segelteam Safram erweitert sein europ\u00e4isches Regattaprogramm - Safram","isPartOf":{"@id":"https:\/\/www.safram.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/#primaryimage"},"image":{"@id":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/#primaryimage"},"thumbnailUrl":"https:\/\/www.safram.com\/wp-content\/uploads\/2019\/12\/1.jpg","datePublished":"2016-05-18T22:00:00+00:00","dateModified":"2019-12-11T16:39:50+00:00","breadcrumb":{"@id":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/#primaryimage","url":"https:\/\/www.safram.com\/wp-content\/uploads\/2019\/12\/1.jpg","contentUrl":"https:\/\/www.safram.com\/wp-content\/uploads\/2019\/12\/1.jpg","width":1024,"height":565},{"@type":"BreadcrumbList","@id":"https:\/\/www.safram.com\/de\/das-schweizer-segelteam-safram-erweitert-sein-europaeisches-regattaprogramm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.safram.com\/de\/"},{"@type":"ListItem","position":2,"name":"Das Schweizer Segelteam Safram erweitert sein europ\u00e4isches Regattaprogramm"}]},{"@type":"WebSite","@id":"https:\/\/www.safram.com\/de\/#website","url":"https:\/\/www.safram.com\/de\/","name":"Safram","description":"Transporteur au coeur de l&#039;Europe","publisher":{"@id":"https:\/\/www.safram.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.safram.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.safram.com\/de\/#organization","name":"Safram","url":"https:\/\/www.safram.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.safram.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.safram.com\/wp-content\/uploads\/2019\/12\/SAFRAM-LOGO.jpg","contentUrl":"https:\/\/www-test.safram.com\/wp-content\/uploads\/2019\/12\/SAFRAM-LOGO.jpg","width":567,"height":422,"caption":"Safram"},"image":{"@id":"https:\/\/www.safram.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SaframFrance"]},{"@type":"Person","@id":"https:\/\/www.safram.com\/de\/#\/schema\/person\/5d3385f3956391d02bb98501605b1e39","name":"symediane","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/aefaa550902b15b2c9beefb2a61934066e2a80665a770df239dcf4ea3547192c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aefaa550902b15b2c9beefb2a61934066e2a80665a770df239dcf4ea3547192c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aefaa550902b15b2c9beefb2a61934066e2a80665a770df239dcf4ea3547192c?s=96&d=mm&r=g","caption":"symediane"}}]}},"_links":{"self":[{"href":"https:\/\/www.safram.com\/de\/wp-json\/wp\/v2\/posts\/3709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.safram.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.safram.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.safram.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.safram.com\/de\/wp-json\/wp\/v2\/comments?post=3709"}],"version-history":[{"count":0,"href":"https:\/\/www.safram.com\/de\/wp-json\/wp\/v2\/posts\/3709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.safram.com\/de\/wp-json\/wp\/v2\/media\/1163"}],"wp:attachment":[{"href":"https:\/\/www.safram.com\/de\/wp-json\/wp\/v2\/media?parent=3709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.safram.com\/de\/wp-json\/wp\/v2\/categories?post=3709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.safram.com\/de\/wp-json\/wp\/v2\/tags?post=3709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}